{"id":58,"count":2,"description":"","link":"https:\/\/www.indiadens.com\/blog\/tag\/root-canal-treatment-cost-in-delhi\/","name":"Root Canal Treatment Cost in Delhi","slug":"root-canal-treatment-cost-in-delhi","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Root Canal Treatment Cost in Delhi Archives - Indiadens<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.indiadens.com\/blog\/tag\/root-canal-treatment-cost-in-delhi\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Root Canal Treatment Cost in Delhi Archives - Indiadens\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.indiadens.com\/blog\/tag\/root-canal-treatment-cost-in-delhi\/\" \/>\n<meta property=\"og:site_name\" content=\"Indiadens\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.indiadens.com\\\/blog\\\/tag\\\/root-canal-treatment-cost-in-delhi\\\/\",\"url\":\"https:\\\/\\\/www.indiadens.com\\\/blog\\\/tag\\\/root-canal-treatment-cost-in-delhi\\\/\",\"name\":\"Root Canal Treatment Cost in Delhi Archives - Indiadens\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.indiadens.com\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.indiadens.com\\\/blog\\\/tag\\\/root-canal-treatment-cost-in-delhi\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.indiadens.com\\\/blog\\\/tag\\\/root-canal-treatment-cost-in-delhi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.indiadens.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Root Canal Treatment Cost in Delhi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.indiadens.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.indiadens.com\\\/blog\\\/\",\"name\":\"Indiadens\",\"description\":\"Dental Tips &amp; Articles\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.indiadens.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.indiadens.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.indiadens.com\\\/blog\\\/#organization\",\"name\":\"Indiadens Dental Clinic\",\"url\":\"https:\\\/\\\/www.indiadens.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.indiadens.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.indiadens.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/indiadens-dental-clinic-logo.png\",\"contentUrl\":\"https:\\\/\\\/www.indiadens.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/indiadens-dental-clinic-logo.png\",\"width\":233,\"height\":86,\"caption\":\"Indiadens Dental Clinic\"},\"image\":{\"@id\":\"https:\\\/\\\/www.indiadens.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/indiadens\\\/\",\"https:\\\/\\\/www.instagram.com\\\/indiadensdelhi\\\/\",\"https:\\\/\\\/in.linkedin.com\\\/in\\\/ujjwal-gulati-19642528\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC6d1KzPhFKBdKQ8FucEVQ4Q\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Root Canal Treatment Cost in Delhi Archives - Indiadens","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.indiadens.com\/blog\/tag\/root-canal-treatment-cost-in-delhi\/","og_locale":"en_US","og_type":"article","og_title":"Root Canal Treatment Cost in Delhi Archives - Indiadens","og_url":"https:\/\/www.indiadens.com\/blog\/tag\/root-canal-treatment-cost-in-delhi\/","og_site_name":"Indiadens","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.indiadens.com\/blog\/tag\/root-canal-treatment-cost-in-delhi\/","url":"https:\/\/www.indiadens.com\/blog\/tag\/root-canal-treatment-cost-in-delhi\/","name":"Root Canal Treatment Cost in Delhi Archives - Indiadens","isPartOf":{"@id":"https:\/\/www.indiadens.com\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/www.indiadens.com\/blog\/tag\/root-canal-treatment-cost-in-delhi\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.indiadens.com\/blog\/tag\/root-canal-treatment-cost-in-delhi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.indiadens.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Root Canal Treatment Cost in Delhi"}]},{"@type":"WebSite","@id":"https:\/\/www.indiadens.com\/blog\/#website","url":"https:\/\/www.indiadens.com\/blog\/","name":"Indiadens","description":"Dental Tips &amp; Articles","publisher":{"@id":"https:\/\/www.indiadens.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.indiadens.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.indiadens.com\/blog\/#organization","name":"Indiadens Dental Clinic","url":"https:\/\/www.indiadens.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.indiadens.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.indiadens.com\/blog\/wp-content\/uploads\/2022\/03\/indiadens-dental-clinic-logo.png","contentUrl":"https:\/\/www.indiadens.com\/blog\/wp-content\/uploads\/2022\/03\/indiadens-dental-clinic-logo.png","width":233,"height":86,"caption":"Indiadens Dental Clinic"},"image":{"@id":"https:\/\/www.indiadens.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/indiadens\/","https:\/\/www.instagram.com\/indiadensdelhi\/","https:\/\/in.linkedin.com\/in\/ujjwal-gulati-19642528","https:\/\/www.youtube.com\/channel\/UC6d1KzPhFKBdKQ8FucEVQ4Q"]}]}},"_links":{"self":[{"href":"https:\/\/www.indiadens.com\/blog\/wp-json\/wp\/v2\/tags\/58","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.indiadens.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.indiadens.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.indiadens.com\/blog\/wp-json\/wp\/v2\/posts?tags=58"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}